{"id":4936,"date":"2021-01-27T09:13:30","date_gmt":"2021-01-27T08:13:30","guid":{"rendered":"https:\/\/www.textmaster.com\/blog\/?p=4936"},"modified":"2021-01-27T10:19:43","modified_gmt":"2021-01-27T09:19:43","slug":"5-grandes-tendances-retail-physique-digital-2021","status":"publish","type":"post","link":"https:\/\/fr.textmaster.com\/blog\/5-grandes-tendances-retail-physique-digital-2021\/","title":{"rendered":"5 grandes tendances du retail physique et digital pour 2021"},"content":{"rendered":"<p>Comme vous le savez s\u00fbrement, l\u2019\u00e9dition 2020 de la <strong>Paris Retail Week<\/strong> a \u00e9t\u00e9 totalement<strong> digitalis\u00e9e <\/strong>et diffus\u00e9e sur sa plateforme digitale, <strong>Paris Retail Week Connect<\/strong>. En effet, au vu de la r\u00e9glementation sanitaire et de ses cons\u00e9quences, il \u00e9tait pr\u00e9f\u00e9rable pour la sant\u00e9 de tous de r\u00e9inventer l\u2019\u00e9v\u00e9nement.<\/p>\n<p>Cependant, et comme tous les ans depuis la cr\u00e9ation de cet \u00e9v\u00e9nement annuel, David Mingeon, directeur g\u00e9n\u00e9ral adjoint d\u2019<strong>Havas Paris<\/strong> a tout de m\u00eame d\u00e9voil\u00e9 les r\u00e9sultats de l\u2019\u00e9tude <strong>Shopper Observer<\/strong>. C\u2019est l\u2019occasion d\u2019en savoir plus sur les <strong>5 grandes tendances<\/strong> <strong>du retail<\/strong> <strong>pour 2021<\/strong> qui caract\u00e9risent le <strong>nouveau comportement de consommation<\/strong> depuis la crise sanitaire. En effet, <strong>58 % des consommateurs<\/strong> estiment que la crise sanitaire aura un <strong>impact positif<\/strong> sur notre mani\u00e8re de consommer et <strong>81 %<\/strong> sont pr\u00eats \u00e0 <strong>d\u00e9laisser une marque <\/strong>si elle ne partageait plus <strong>leurs valeurs<\/strong>. Il semblerait que cette nouvelle \u00e8re acc\u00e9l\u00e8re les processus en mati\u00e8re de consommation.<\/p>\n<p>Alors qu\u2019en sera-t-il ?<\/p>\n<hr \/>\n<p><a href=\"https:\/\/go.textmaster.com\/lp-fr-international-stories\"><strong>Et pour un retail plus international, n\u2019h\u00e9sitez pas \u00e0 d\u00e9couvrir des t\u00e9moignages dans notre e-book International Stories !<\/strong><\/a><\/p>\n<hr \/>\n<p>Souvenez-vous, l\u2019ann\u00e9e derni\u00e8re David Mingeon a d\u00e9clar\u00e9<em> \u00ab <strong>Les retailers sont contraints \u00e0 faire bouger les lignes <\/strong>\u00bb. <\/em>Une phrase qui prendra encore plus de sens dor\u00e9navant.<\/p>\n<p>Quelles sont les nouvelles facettes du consommateur ? Plus local, plus responsable ? Nous vous disons tout ! D\u00e9couvrez d\u00e8s maintenant les grandes tendances retail \u00e0 suivre en 2021.<\/p>\n<h2>Le retour de la consommation locale : la fin des grandes marques ?<\/h2>\n<p>La crise sanitaire a renforc\u00e9 ce d\u00e9sir de proximit\u00e9 et ce besoin de consommer plus de produits <strong>locaux et artisanaux<\/strong>. Le consommateur mise sur la <strong>proximit\u00e9<\/strong>. En effet, <strong>92 %<\/strong> <strong>des consommateurs fran\u00e7ais se disent pr\u00eats \u00e0 plus \u00ab consommer local \u00bb<\/strong> et <strong>89 %<\/strong> <strong>souhaitent se tourner davantage vers les<\/strong> <strong>produits artisanaux<\/strong>. Consommer local est devenu un v\u00e9ritable mode de vie et est per\u00e7u comme une <strong>garantie de qualit\u00e9<\/strong> permettant de renouer avec les valeurs d\u2019<strong>authenticit\u00e9<\/strong>.<\/p>\n<p>Vous l\u2019aurez compris, le local s\u00e9duit de plus en plus et est, pour les consommateurs, <strong>gage d\u2019\u00e9cologie et de transparence<\/strong> : des facteurs importants \u00e0 prendre en compte, ce qui n\u2019a pas \u00e9chapp\u00e9 aux grandes enseignes qui se sentent \u00e0 pr\u00e9sent oblig\u00e9es de s \u2018y mettre aussi.<\/p>\n<p>Cependant, il reste un frein. <strong>L\u2019authentique co\u00fbte cher<\/strong>, et ce, pour <strong>68 % des consommateurs fran\u00e7ais qui estiment que les prix de ces produits restent bien plus \u00e9lev\u00e9s que les produits de grandes marques<\/strong>. Le local arrivera-t-il \u00e0 satisfaire tous les consommateurs ?&#8230;<\/p>\n<p>Le sujet soul\u00e8ve pas mal de questions : ce ph\u00e9nom\u00e8ne signifierait-il la fin de la grande consommation \u00e0 l\u2019international ? Serait-ce le d\u00e9but de la fin pour les grandes marques comme Nike, Coca-Cola ou encore Nutella ? En tout cas, cela pourrait \u00eatre le cas pour la majeure partie des consommateurs. Aujourd\u2019hui, <strong>60 % se disent pr\u00eats \u00e0 se passer des grandes marques nationales et internationales<\/strong>.<\/p>\n<p>Pourtant, tout cela reste malgr\u00e9 tout assez paradoxal lorsque l\u2019on voit que des consommateurs continuent d\u2019acheter des produits industriels. Pour preuve, <strong>Nutella a recrut\u00e9 plus d\u2019un million de nouveaux clients durant la p\u00e9riode de confinement<\/strong> ! Alors qu\u2019en est-il vraiment ?<\/p>\n<p>C\u2019est une grande remise en question qui s\u2019impose pour les grandes enseignes qui, jusqu\u2019\u00e0 pr\u00e9sent, se reposaient sur leur forte notori\u00e9t\u00e9. Il est temps pour les grandes marques de <strong>devenir encore plus proches de leurs clients<\/strong> !<\/p>\n<h2>Entre impatience et prise de conscience, tout s\u2019acc\u00e9l\u00e8re<\/h2>\n<p>Commen\u00e7ons avec des chiffres : <strong>65 % des consommateurs sont pr\u00eats \u00e0 payer plus cher un produit disponible imm\u00e9diatement<\/strong> et <strong>73 % des fran\u00e7ais sont pr\u00eats \u00e0 changer de marque pour un produit \u00e9quivalent disponible plus rapidement<\/strong>. Vous l\u2019aurez compris, la rapidit\u00e9 d\u2019acc\u00e8s aux produits devient, apr\u00e8s plusieurs ann\u00e9es, un <strong>crit\u00e8re d\u00e9terminant de l\u2019offre<\/strong>. 1 consommateur sur 3 utilise des offres de <a href=\"https:\/\/fr.textmaster.com\/blog\/logistique-internationale\/\">livraison<\/a> rapide : la mise \u00e0 disposition rapide de ses achats fait une grosse diff\u00e9rence.<\/p>\n<p>Le d\u00e9lai de livraison id\u00e9al d\u2019une commande sur internet est de <strong>24 \u00e0 48h<\/strong>. Une exigence qui impose de gros d\u00e9fis logistiques auxquels doivent faire face les retailers. Par cons\u00e9quent, les marques continuent leur comp\u00e9tition pour <strong>diminuer le temps entre la prise de commande et la livraison<\/strong>. Mais ces nouvelles m\u00e9thodes de consommation dues au d\u00e9sir d\u2019imm\u00e9diatet\u00e9 ne sont pas sans cons\u00e9quences sur la plan\u00e8te.<\/p>\n<p>Qu\u2019en est-il c\u00f4t\u00e9 environnement ? <strong>Plus la livraison est rapide, plus l\u2019impact carbone est fort<\/strong>. Peu d\u2019acteurs aujourd\u2019hui agissent pour des livraisons vraiment responsables. En effet, <strong>67 % d\u00e9clarent avoir une mauvaise conscience en ce qui concerne la livraison rapide<\/strong>. Du c\u00f4t\u00e9 des consommateurs, la tendance est un peu diff\u00e9rente. Certains ont quand m\u00eame plus conscience des cons\u00e9quences environnementales et sociales caus\u00e9es par leurs choix. Mais seront-ils pr\u00eats \u00e0 accepter <strong>une majoration de prix ou une compensation \u00e9cologique<\/strong> en fonction du degr\u00e9 d\u2019urgence de la livraison souhait\u00e9e ? \u2026<\/p>\n<p>Le succ\u00e8s de plusieurs nouveaux acteurs du monde de la mode en ligne, notamment, t\u00e9moigne d\u2019une prise de conscience \u00e9cologique chez certains consommateurs. Asphalte, marque de v\u00eatements pour hommes, a par exemple d\u00e9cid\u00e9 de ne <strong>pas entrer dans la logique de collection automne\/hiver ni de soldes afin de ne pas encourager le<\/strong> <strong>fast fashion<\/strong> ; d\u2019autres marques choisissent de ne pas proposer de livraison en 24 ou 48h, ou de livraison gratuite.<\/p>\n<p><strong>Renverser les tendances actuelles pour se d\u00e9marquer et r\u00e9inventer son secteur<\/strong> : une prise de position qui fonctionne sans doute pour certaines marques ou certaines cibles, mais qui a le m\u00e9rite en tous les cas de faire r\u00e9fl\u00e9chir aux nouveaux modes de consommation et \u00e0 leurs impacts sur la plan\u00e8te.<\/p>\n<h2>Entre fid\u00e9lit\u00e9, infid\u00e9lit\u00e9 et valeurs\u2026<\/h2>\n<blockquote><p>\u00ab <em>Les marques et les enseignes ne doivent jamais oublier que <strong>consommer c\u2019est partager une relation intime, \u00e9quilibr\u00e9e<\/strong> et que plus que jamais les valeurs d\u00e9fendues par les marques apparaissent comme le meilleur levier de fid\u00e9lisation.<\/em> \u00bb<\/p>\n<p>David Mingeon, Directeur G\u00e9n\u00e9ral Adjoint, Havas Paris.<\/p><\/blockquote>\n<p>Les consommateurs ont un d\u00e9sir de nouveaut\u00e9. De ce fait, le concept de <strong>fid\u00e9lit\u00e9<\/strong> ne semble plus \u00eatre aussi important qu\u2019avant. <strong>71 % des consommateurs ont le sentiment que les programmes de fid\u00e9lit\u00e9 se ressemblent tous<\/strong>. Les raisons qui poussent un consommateur \u00e0 \u00eatre infid\u00e8le \u00e0 une marque sont multiples : probl\u00e8mes de qualit\u00e9, le prix ou encore l\u2019envie de d\u00e9couvrir de nouvelles choses.<\/p>\n<p>En effet, fid\u00e9liser un client ce n\u2019est plus simplement cr\u00e9er un sentiment de \u00ab r\u00e9compense \u00bb, c\u2019est \u00e9galement <strong>cr\u00e9er un sentiment de reconnaissance et d\u2019appartenance<\/strong>.<\/p>\n<p>La question \u00e0 se poser n\u2019est plus \u00ab quel programme de fid\u00e9lisation dois-je proposer ? \u00bb, mais plut\u00f4t \u00ab <strong>comment faire pour engager mes clients \u00e0 rester sur le long terme ?<\/strong> \u00bb. Pour cela, la fid\u00e9lisation doit d\u00e9passer le stade de la simple transaction.<\/p>\n<p>Aujourd\u2019hui, les enseignes tentent d\u2019exploiter de nouvelles voies comme <strong>l\u2019ultra transparence <\/strong>o\u00f9 la collecte de donn\u00e9es est maintenant lisible et mon\u00e9tisable par le consommateur. Prochainement, les tests ADN pourraient \u00e9galement faire leur grande apparition dans le monde du retail. Ce sont d\u00e9j\u00e0 <strong>26 % des consommateurs qui se disent pr\u00eats \u00e0 partager leur ADN avec les marques<\/strong> afin d\u2019avoir acc\u00e8s \u00e0 des produits sur-mesure.<\/p>\n<h2>La notion de marketing de d\u00e9consommation<\/h2>\n<p>\u00ab <strong>Consommer moins mais mieux<\/strong> \u00bb, un leitmotiv qui revient souvent. La d\u00e9consommation est un ph\u00e9nom\u00e8ne ayant \u00e9merg\u00e9 avant la crise et s\u2019acc\u00e9l\u00e8re depuis celle-ci. Nous faisons face ici \u00e0 des consommateurs qui ne veulent plus consommer autant. De plus, <strong>42 % ont le sentiment de moins consommer qu\u2019avant et 78 % des fran\u00e7ais pensent que la surconsommation pourrait entra\u00eener un effondrement de notre civilisation<\/strong>. La Covid-19 n\u2019en serait que les pr\u00e9mices.<\/p>\n<p>Cette \u00ab tendance \u00bb donne des id\u00e9es et n\u2019\u00e9chappe pas aux marques et enseignes qui tentent tant bien que mal de jouer sur la transparence tout en invitant leurs clients \u00e0 moins consommer.<\/p>\n<p>Vous l\u2019aurez compris, face \u00e0 des consommateurs r\u00e9ceptifs et sensibles, <strong>jouer avec les craintes<\/strong> en communiquant sur des lendemains incertains est un bon moyen de vendre plus. En effet, <strong>66 % des consommateurs se sentent beaucoup plus proches des marques qui ont un engagement contre la consommation excessive<\/strong>. \u00c0 en juger par l\u2019explosion des jeunes marques de beaut\u00e9 ou d\u2019hygi\u00e8ne misant par exemple sur les recharges pour r\u00e9duire la consommation de plastique \u00e0 usage unique ou encore l\u2019absence de packaging etc., la tendance semble tranquillement gagner du terrain.<\/p>\n<p>Entre v\u00e9ritable valeur et tendance, nous ne savons plus vraiment sur quel pied danser car la fronti\u00e8re reste mince pour les marques, qui n\u2019ont pas le droit \u00e0 l\u2019erreur&#8230;<\/p>\n<h2>N\u00e9o-bazars, Qu\u00e9sako ?<\/h2>\n<p><strong>Joom, Shein, Action, Aliexpress, Wish<\/strong> \u2026 Vous savez s\u00fbrement de quoi on parle. Nous sommes quasiment s\u00fbrs que vous avez d\u00e9j\u00e0 command\u00e9 chez l\u2019une de ses enseignes. Quoi de mieux qu\u2019un lot de 10 prot\u00e8ge c\u00e2bles pingouins \u00e0 moins de 3 \u20ac pour bien commencer la journ\u00e9e ? <strong>Le discount a le vent en poupe<\/strong> chez les consommateurs.<\/p>\n<p><strong>1 fran\u00e7ais sur 3 se rend au moins une fois par mois sur des plateformes de n\u00e9o-discounters<\/strong>. On parle ici de \u00ab shopping plaisir \u00bb, cette sensation d\u2019avoir plus de pouvoir d\u2019achat et plus de choix accessibles. Pour preuve, <strong>79 % des fran\u00e7ais d\u00e9clarent avoir besoin de temps en temps de faire moins attention et de se faire plaisir<\/strong>, en consommant pour se lib\u00e9rer de la frustration. Prenez, par exemple, l\u2019enseigne <strong>Action : une valorisation \u00e0 10 milliards d\u2019euros, \u00e9quivalente \u00e0 celle de Carrefour<\/strong>. Cet exemple illustre bien le fait que <strong>74 % des consommateurs ressentent du plaisir \u00e0 faire de bonnes affaires<\/strong> en trouvant des produits bon march\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>La Covid-19 comme un amplificateur de tendances d\u00e9j\u00e0 \u00e9mergentes, 2020 aura \u00e9t\u00e9 l\u2019ann\u00e9e de tous les d\u00e9fis entre <strong>consommation plus rapide, mais aussi plus locale, plus responsable<\/strong>\u2026<\/p>\n<p>\u00ab Les r\u00e9sultats du Shopper Observer 2020 nous montrent des tendances qui, bien qu\u2019initi\u00e9es avant le Covid, se sont encore acc\u00e9l\u00e9r\u00e9es avec la crise : <strong>une consommation plus engag\u00e9e et responsable avec cependant quelques \u00ab soupapes de d\u00e9compression \u00bb<\/strong> qui r\u00e9v\u00e8lent tout le paradoxe fa\u00e7onn\u00e9 et encourag\u00e9 par notre soci\u00e9t\u00e9 de consommation. \u00bb souligne Arnaud Gallet, Directeur du salon Paris Retail Week.<\/p>\n<p>Ce qu\u2019il faut retenir face \u00e0 ce retour \u00e0 l\u2019essentiel, c\u2019est que le consommateur n\u2019est cependant pas encore pr\u00eat \u00e0 arr\u00eater de se faire plaisir. Qu\u2019en sera-t-il vraiment au cours de l\u2019ann\u00e9e ? Allez-vous suivre ces tendances retail en 2021 ?<\/p>\n<p>&nbsp;<\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-5799e19c-dc42-413b-9ecf-b624338fbc63\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-5799e19c-dc42-413b-9ecf-b624338fbc63\" class=\"hs-cta-node hs-cta-5799e19c-dc42-413b-9ecf-b624338fbc63\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/2680086\/5799e19c-dc42-413b-9ecf-b624338fbc63\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" id=\"hs-cta-img-5799e19c-dc42-413b-9ecf-b624338fbc63\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/2680086\/5799e19c-dc42-413b-9ecf-b624338fbc63.png\" alt=\"International Stories : 8 t\u00e9moignages pour d\u00e9couvrir les secrets de la r\u00e9ussite \u00e0 l'international\" width=\"750\" height=\"200\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(2680086, '5799e19c-dc42-413b-9ecf-b624338fbc63', {}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez s\u00fbrement, l\u2019\u00e9dition 2020 de la <strong>Paris Retail Week<\/strong> a \u00e9t\u00e9 totalement<strong> digitalis\u00e9e <\/strong>et diffus\u00e9e sur sa plateforme digitale, <strong>Paris Retail Week Connect<\/strong>. En effet, au vu de la r\u00e9glementation sanitaire et de ses cons\u00e9quences, il \u00e9tait pr\u00e9f\u00e9rable pour la sant\u00e9 de tous de r\u00e9inventer l\u2019\u00e9v\u00e9nement.<\/p>\n<p>Cependant, et comme tous les ans depuis la cr\u00e9ation de cet \u00e9v\u00e9nement annuel, David Mingeon, directeur g\u00e9n\u00e9ral adjoint d\u2019<strong>Havas Paris<\/strong> a tout de m\u00eame d\u00e9voil\u00e9 les r\u00e9sultats de l\u2019\u00e9tude <strong>Shopper Observer<\/strong>. C\u2019est [&#8230;]<\/p>\n","protected":false},"author":22,"featured_media":4944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,13],"tags":[],"_links":{"self":[{"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/posts\/4936"}],"collection":[{"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/comments?post=4936"}],"version-history":[{"count":3,"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/posts\/4936\/revisions"}],"predecessor-version":[{"id":4948,"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/posts\/4936\/revisions\/4948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/media\/4944"}],"wp:attachment":[{"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/media?parent=4936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/categories?post=4936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.textmaster.com\/blog\/wp-json\/wp\/v2\/tags?post=4936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}